{"id":3,"date":"2021-02-26T15:30:06","date_gmt":"2021-02-26T18:30:06","guid":{"rendered":"https:\/\/lojashopbase.com.br\/spark\/?page_id=3"},"modified":"2021-09-30T17:25:57","modified_gmt":"2021-09-30T20:25:57","slug":"politica-de-privacidade","status":"publish","type":"page","link":"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/","title":{"rendered":"Pol\u00edtica de Privacidade"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15e3571 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15e3571\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a18a22c\" data-id=\"a18a22c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d12c0ac elementor-widget elementor-widget-heading\" data-id=\"d12c0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de Privacidade<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3571a719 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3571a719\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72ef1732\" data-id=\"72ef1732\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34245539 elementor-widget elementor-widget-text-editor\" data-id=\"34245539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Pol\u00edtica de Privacidade On-Line do site da <strong><\/strong>\u00a0foi criada para respeitar a LGPD (<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2018\/lei\/L13709.htm\" target=\"_blank\" rel=\"noopener\">Lei Geral de Prote\u00e7\u00e3o de Dados<\/a>) e afirmar o nosso compromisso com a seguran\u00e7a e a privacidade das informa\u00e7\u00f5es coletadas dos visitantes de nosso site. Esta pol\u00edtica est\u00e1 sujeita a eventuais atualiza\u00e7\u00f5es e recomendamos que ela seja consultada periodicamente. Voc\u00ea pode visitar nosso site e conhecer nossos servi\u00e7os e produtos, verificar nossas ofertas, ler artigos, obter informa\u00e7\u00f5es e suporte sem precisar fornecer nenhuma informa\u00e7\u00e3o pessoal. Mas, caso isso aconte\u00e7a, esta pol\u00edtica procura esclarecer como coletamos e tratamos seus dados pessoais.<\/p>\n<h2>Como tratamos os dados<\/h2>\n<ol>\n<li>Qualquer informa\u00e7\u00e3o fornecida pelos usu\u00e1rios ser\u00e1 coletada e guardada de acordo com os padr\u00f5es atuais de seguran\u00e7a e confiabilidade.<\/li>\n<li>Utilizamos em nosso site o protocolo padr\u00e3o HTTPS que garante que todas as informa\u00e7\u00f5es coletadas dos usu\u00e1rios trafeguem de forma segura, utilizando processo de criptografia padr\u00e3o da Internet.<\/li>\n<li>As informa\u00e7\u00f5es pessoais que nos forem fornecidas ser\u00e3o coletadas por meios legais. Essa coleta ter\u00e1 o prop\u00f3sito de comunica\u00e7\u00e3o comercial para que possamos vender nossos servi\u00e7os, produtos, prestar suporte a atendimento sobre eles.<\/li>\n<li>A menos que tenhamos determina\u00e7\u00e3o legal ou judicial, as informa\u00e7\u00f5es dos usu\u00e1rios jamais ser\u00e3o fornecidas a terceiros ou usadas para finalidades diferentes daquelas para as quais foram coletadas.<\/li>\n<li>O acesso as informa\u00e7\u00f5es coletadas est\u00e1 restrito apenas aos gestores da <strong><\/strong> e manteremos a integridade das informa\u00e7\u00f5es que nos forem fornecidas.<\/li>\n<li>Eventualmente, poderemos utilizar cookies (*) para confirmar sua identidade, personalizar seu acesso e acompanhar a utiliza\u00e7\u00e3o de nosso website visando o aprimoramento de sua navega\u00e7\u00e3o e funcionalidade.<\/li>\n<li>Colocamos \u00e0 disposi\u00e7\u00e3o de nossos usu\u00e1rios, canais de atendimento ao cliente, para esclarecer qualquer d\u00favida que possa surgir referente aos seus dados. Estes canais podem ser acionados atrav\u00e9s do e-mail  ou do nosso <a href=\"https:\/\/lojashopbase.com.br\/spark\/contato\/\">Formul\u00e1rio de contato<\/a>.<\/li>\n<\/ol>\n<h2>Como coletamos os dados<\/h2>\n<ul>\n<li>Atrav\u00e9s dos rastreadores e cookies dos servi\u00e7os de marketing e SEO da <strong>Google<\/strong>. Estas ferramentas coletam dados an\u00f4nimos como a sua localiza\u00e7\u00e3o, seu IP, rastreia a navega\u00e7\u00e3o e analisa o seu comportamento em nosso site a fim de nos fornecer relat\u00f3rios sobre os servi\u00e7os e produtos que voc\u00ea procurou e qual a origem da sua visita; pesquisa do Google, acesso direto ou link existente em outro site, a <strong><\/strong> respeita a pol\u00edtica de privacidade da Google, para mais informa\u00e7\u00f5es leia a Pol\u00edtica diretamente no site da Google.<\/li>\n<li><strong>Pixel do Facebook.<\/strong> Monitora as a\u00e7\u00f5es realizadas pelo visitante em nosso site. Como por exemplo; quando voc\u00ea adiciona um item ao carrinho, isso gera um relat\u00f3rio para n\u00f3s. Seus dados pessoais n\u00e3o ser\u00e3o capturados, apenas suas a\u00e7\u00f5es como dados an\u00f4nimos.<\/li>\n<li><strong>Gateways de Pagamento.<\/strong> Vendemos em nosso site produtos e servi\u00e7os que podem ser pagos on-line atr\u00e1ves de Gateways de Pagamento. Este servi\u00e7o de pagamento necessita coletar seus dados pessoais para que possa ser poss\u00edvel executar uma transa\u00e7\u00e3o financeira de forma segura em nosso site, isenta de fraudes e roubo de dados. Nenhum dado referente a cart\u00e3o de cr\u00e9dito ou dados banc\u00e1rios ser\u00e3o armazenados em nosso site, estas informa\u00e7\u00f5es s\u00e3o solicitadas apenas pelo Gateway de Pagamento.<\/li>\n<li><strong>Empresas de Transporte.<\/strong> Para que possamos lhe enviar nossos produtos \u00e9 necess\u00e1rio compartilhar com nossos parceiros de log\u00edstica seus dados pessoais e se necess\u00e1rio c\u00f3pia da Nota Fiscal referente a sua compra. Nos preocupamos em trabalhar com parceiros de confian\u00e7a para garantirmos a seguran\u00e7a de seus dados.<\/li>\n<li><strong>Chat de Atendimento on-Line.<\/strong> Usamos ferramentas de atendimento on-line para disponibilizar um chat ao vivo com nossos atendentes. Para que possamos dar continuidade no seu atendimento \u00e9 necess\u00e1rio coletar seu nome, e-mail e telefone. Estas informa\u00e7\u00f5es permanecer\u00e3o gravadas como um hist\u00f3rico e s\u00e3o removidas caso o cliente solicite ou depois de 1 ano de armazenamento.<\/li>\n<li><strong>WhatsApp.<\/strong> O visitante ao acionar o bot\u00e3o do WhatsApp disponibilizado em nosso site dever\u00e1 ter ci\u00eancia de que teremos acesso ao seu nome e n\u00famero de celular, podendo a <strong><\/strong> armazenar esta informa\u00e7\u00e3o para contatos comerciais futuros. Voc\u00ea poder\u00e1 bloquear nosso contato caso n\u00e3o julgue conveniente e\/ou solicitar a remo\u00e7\u00e3o de nossa lista de contatos do WhatsApp.<\/li>\n<li><strong>Chat do Facebook.<\/strong> O visitante ao acionar o bot\u00e3o de cat do Facebook disponibilizado em nosso site dever\u00e1 ter ci\u00eancia de que teremos acesso ao seu nome e e-mail, podendo a <strong><\/strong> armazenar esta informa\u00e7\u00e3o para contatos comerciais futuros. Voc\u00ea poder\u00e1 bloquear nosso contato caso n\u00e3o julgue conveniente ou solicitar a remo\u00e7\u00e3o de nossa lista de contatos.<\/li>\n<li><strong>Google Forms.<\/strong> Eventualmente podemos coletar dados referente aos nossos servi\u00e7os e realizar pesquisas atrav\u00e9s do servi\u00e7o de coletada de dados por formul\u00e1rios do Google Forms. Durante a coleta dos dados poder\u00e1 ser\u00e1 solicitado nome completo, telefone, e-mail e informa\u00e7\u00f5es triviais sobre o seu neg\u00f3cio.<\/li>\n<li><strong>Cookies do site.<\/strong> Necessitamos criar cookies (pequenos arquivos de texto que podem definir prefer\u00eancias) no computador ou dispositivo do visitante para fornecer uma experi\u00eancia mais agrad\u00e1vel de navega\u00e7\u00e3o baseado na coleta de dados an\u00f4nimos. Os cookies definem, por exemplo, o cache do servidor para que a navega\u00e7\u00e3o se torna mais r\u00e1pida e flu\u00edda. Importante! Cookies n\u00e3o coletam informa\u00e7\u00f5es pessoais suas, nem nos permite acessar arquivos e programas de seu computador. Voc\u00ea pode remover os cookies a qualquer momento limpando o hist\u00f3rico do seu navegador.<\/li>\n<li><strong>Notifica\u00e7\u00f5es via Push.<\/strong> Voc\u00ea pode permitir que o nosso site lhe envie notifica\u00e7\u00f5es em seu computador ou celular atrav\u00e9s do seu navegador usando o servi\u00e7o de Push Notification. Voc\u00ea somente receber\u00e1 nossas notifica\u00e7\u00f5es ap\u00f3s se inscrever de forma volunt\u00e1ria em nosso canal. Voc\u00ea pode para de receber nossas notifica\u00e7\u00f5es a qualquer momento revendo as configura\u00e7\u00f5es do seu navegador ou dispositivo m\u00f3vel. Para saber como proceder, acesse este tutorial passo a passo.<\/li>\n<\/ul>\n<h2>Consentimento ou Bloqueio de Cookies<\/h2>\n<p>Para que os recursos de coleta de dados em nosso site funcione adequadamente \u00e9 necess\u00e1rio o uso de cookies (pequenos arquivos de texto que podem definir prefer\u00eancias). Os cookies n\u00e3o s\u00e3o programas, n\u00e3o roubam dados de seu computador e n\u00e3o colocam a sua navega\u00e7\u00e3o em risco, no entanto, \u00e9 de seu direito bloquear nossos cookies caso queira. Para saber como proceder, acesse este tutorial passo a passo.<\/p>\n<h2>Seus Direitos<\/h2>\n<p>Voc\u00ea tem os seguintes direitos:<\/p>\n<ul>\n<li>O direito de bloquear qualquer tipo de rastreador e cookie gerado em nosso site de modo a n\u00e3o compartilhar nenhum tipo de informa\u00e7\u00e3o sobre a sua conex\u00e3o e acesso ao nosso site.<\/li>\n<li>O direito de nos pedir para atualizar qualquer informa\u00e7\u00e3o pessoal incorreta de que temos sobre voc\u00ea.<\/li>\n<li>O direito de optar por sair de quaisquer meios de comunica\u00e7\u00e3o comercial e de marketing.<\/li>\n<li>O direito de pedir a remo\u00e7\u00e3o de qualquer dado pessoal que tenhamos armazenado sobre voc\u00ea.<\/li>\n<\/ul>\n<p>Reservamos o prazo de 5 dias \u00fateis para lhe responder sobre qualquer contato referente aos seus dados pessoais, podendo este prazo ser estendido em per\u00edodo de festas, feriados prolongados, recesso e f\u00e9rias coletivas.<\/p>\n<p style=\"text-align: right\"><em> Esta pol\u00edtica de Privacidade foi atualizada em 15\/09\/2021<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidade<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Privacidade - Root<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidade - Root\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de Privacidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Root\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T20:25:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/politica-de-privacidade\\\/\",\"url\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/politica-de-privacidade\\\/\",\"name\":\"Pol\u00edtica de Privacidade - Root\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/#website\"},\"datePublished\":\"2021-02-26T18:30:06+00:00\",\"dateModified\":\"2021-09-30T20:25:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/politica-de-privacidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/politica-de-privacidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/politica-de-privacidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/#website\",\"url\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/\",\"name\":\"Root\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidade - Root","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Pol\u00edtica de Privacidade - Root","og_description":"Pol\u00edtica de Privacidade","og_url":"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/","og_site_name":"Root","article_modified_time":"2021-09-30T20:25:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/","url":"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/","name":"Pol\u00edtica de Privacidade - Root","isPartOf":{"@id":"https:\/\/lojashopbase.com.br\/spark\/#website"},"datePublished":"2021-02-26T18:30:06+00:00","dateModified":"2021-09-30T20:25:57+00:00","breadcrumb":{"@id":"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lojashopbase.com.br\/spark\/politica-de-privacidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojashopbase.com.br\/spark\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidade"}]},{"@type":"WebSite","@id":"https:\/\/lojashopbase.com.br\/spark\/#website","url":"https:\/\/lojashopbase.com.br\/spark\/","name":"Root","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojashopbase.com.br\/spark\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}