{"id":331,"date":"2021-03-05T09:53:38","date_gmt":"2021-03-05T12:53:38","guid":{"rendered":"https:\/\/lojashopbase.com.br\/spark\/?page_id=331"},"modified":"2021-09-30T17:26:08","modified_gmt":"2021-09-30T20:26:08","slug":"termos-de-uso","status":"publish","type":"page","link":"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/","title":{"rendered":"Termos de Uso"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"331\" class=\"elementor elementor-331\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15e3571 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15e3571\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a18a22c\" data-id=\"a18a22c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d12c0ac elementor-widget elementor-widget-heading\" data-id=\"d12c0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Termos de Uso<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3571a719 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3571a719\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72ef1732\" data-id=\"72ef1732\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34245539 elementor-widget elementor-widget-text-editor\" data-id=\"34245539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>VIS\u00c3O GERAL<\/p>\n<p>Este site \u00e9 operado pela . Em todo o site, os termos &#8220;n\u00f3s&#8221;, &#8220;n\u00f3s&#8221; e &#8220;nosso&#8221; se referem \u00e0 .  oferece este site, incluindo todas as informa\u00e7\u00f5es, ferramentas e servi\u00e7os dispon\u00edveis neste site, para voc\u00ea, o usu\u00e1rio, mediante a sua aceita\u00e7\u00e3o de todos os termos, condi\u00e7\u00f5es, pol\u00edticas e avisos estabelecidos aqui.<\/p>\n<p>Ao visitar nosso site e\/ou comprar alguma coisa no nosso site, voc\u00ea est\u00e1 utilizando nossos \u201cServi\u00e7os\u201d e, consequentemente, concorda com os seguintes termos e condi\u00e7\u00f5es (\u201cTermos de servi\u00e7o\u201d, \u201cTermos\u201d), incluindo os termos e condi\u00e7\u00f5es e pol\u00edticas adicionais mencionados neste documento e\/ou dispon\u00edveis por hyperlink. Esses Termos de servi\u00e7o se aplicam a todos os usu\u00e1rios do site, incluindo, entre outros, os usu\u00e1rios que s\u00e3o visualizadores, fabricantes, clientes, lojistas e\/ou colaboradores de conte\u00fado. Leia estes Termos de servi\u00e7o cuidadosamente antes de acessar ou utilizar o nosso site. Ao acessar ou usar qualquer parte do site, voc\u00ea concorda com os Termos de servi\u00e7o. Se voc\u00ea n\u00e3o concorda com todos os termos e condi\u00e7\u00f5es deste contrato, ent\u00e3o voc\u00ea n\u00e3o pode acessar o site ou usar quaisquer servi\u00e7os. Se esses Termos de servi\u00e7o s\u00e3o considerados uma oferta, a aceita\u00e7\u00e3o \u00e9 expressamente limitada a esses Termos de servi\u00e7o.<\/p>\n<p>Quaisquer novos recursos ou ferramentas que forem adicionados \u00e0 loja atual tamb\u00e9m devem estar sujeitos aos Termos de servi\u00e7o. Voc\u00ea pode revisar a vers\u00e3o mais atual dos Termos de servi\u00e7o quando quiser nesta p\u00e1gina. Reservamo-nos o direito de atualizar, alterar ou trocar qualquer parte desses Termos de servi\u00e7o ao publicar atualiza\u00e7\u00f5es e\/ou altera\u00e7\u00f5es no nosso site. \u00c9 sua responsabilidade verificar periodicamente as altera\u00e7\u00f5es feitas nesta p\u00e1gina. Seu uso cont\u00ednuo ou acesso ao site ap\u00f3s a publica\u00e7\u00e3o de quaisquer altera\u00e7\u00f5es constitui aceita\u00e7\u00e3o de tais altera\u00e7\u00f5es.Nossa loja est\u00e1 hospedada na Shopify Inc. Esta empresa nos fornece a plataforma de e-commerce online que nos permite vender nossos produtos e servi\u00e7os para voc\u00ea.<\/p>\n<p><strong>SE\u00c7\u00c3O 1 &#8211; TERMOS DA LOJA VIRTUAL<\/strong><\/p>\n<p>Ao concordar com estes Termos de servi\u00e7o, voc\u00ea declara que tem idade m\u00ednima de maioridade em seu estado ou munic\u00edpio de resid\u00eancia, ou que \u00e9 maior de idade em seu estado ou munic\u00edpio de resid\u00eancia, e que nos deu sua permiss\u00e3o para permitir que qualquer um de seus dependentes menores use este site.<\/p>\n<p>Voc\u00ea n\u00e3o deve usar nossos produtos para qualquer fim ilegal ou n\u00e3o autorizado. Voc\u00ea tamb\u00e9m n\u00e3o pode, ao usufruir deste Servi\u00e7o, violar quaisquer leis em sua jurisdi\u00e7\u00e3o (incluindo, entre outras, as leis de direitos autorais).<\/p>\n<p>Voc\u00ea n\u00e3o deve transmitir nenhum v\u00edrus ou qualquer c\u00f3digo de natureza destrutiva.<\/p>\n<p>Violar qualquer um dos Termos resultar\u00e1 na rescis\u00e3o imediata dos seus Servi\u00e7os.<\/p>\n<p><strong>SE\u00c7\u00c3O 2 &#8211; CONDI\u00c7\u00d5ES GERAIS<\/strong><\/p>\n<p>Reservamo-nos o direito de recusar o servi\u00e7o a qualquer pessoa, por qualquer motivo, a qualquer momento.<\/p>\n<p>Voc\u00ea entende que o seu conte\u00fado (n\u00e3o incluindo informa\u00e7\u00f5es de cart\u00e3o de cr\u00e9dito) pode ser transferido sem criptografia e pode: (a) ser transmitido por v\u00e1rias redes; e (b) sofrer altera\u00e7\u00f5es para se adaptar e se adequar \u00e0s exig\u00eancias t\u00e9cnicas de conex\u00e3o de redes ou dispositivos. As informa\u00e7\u00f5es de cart\u00e3o de cr\u00e9dito sempre s\u00e3o criptografadas durante a transfer\u00eancia entre redes.<\/p>\n<p>Voc\u00ea concorda em n\u00e3o reproduzir, duplicar, copiar, vender, revender ou explorar qualquer parte do Servi\u00e7o, uso do Servi\u00e7o, acesso ao Servi\u00e7o, ou qualquer contato no site atrav\u00e9s do qual o Servi\u00e7o seja fornecido, sem nossa permiss\u00e3o expressa por escrito.<\/p>\n<p>Os t\u00edtulos usados neste contrato s\u00e3o inclu\u00eddos apenas por conveni\u00eancia e n\u00e3o limitam ou afetam os Termos.<\/p>\n<p><strong>SE\u00c7\u00c3O 3 &#8211; PRECIS\u00c3O, COMPLETUDE E PER\u00cdODO DE VALIDADE DAS INFORMA\u00c7\u00d5ES<\/strong><\/p>\n<p>N\u00e3o nos responsabilizamos se as informa\u00e7\u00f5es disponibilizadas neste site n\u00e3o forem precisas, completas ou atuais. O material deste site \u00e9 fornecido apenas para fins informativos e n\u00e3o deve ser usado como a \u00fanica base para tomar decis\u00f5es sem consultar fontes de informa\u00e7\u00f5es prim\u00e1rias, mais precisas, mais completas ou mais atuais. Qualquer utiliza\u00e7\u00e3o do material deste site \u00e9 por sua conta e risco.<\/p>\n<p>Este site pode conter certas informa\u00e7\u00f5es hist\u00f3ricas. As informa\u00e7\u00f5es hist\u00f3ricas podem n\u00e3o ser atuais e s\u00e3o fornecidas apenas para sua refer\u00eancia. Reservamo-nos o direito de modificar o conte\u00fado deste site a qualquer momento, mas n\u00f3s n\u00e3o temos obriga\u00e7\u00e3o de atualizar nenhuma informa\u00e7\u00e3o em nosso site. Voc\u00ea concorda que \u00e9 de sua responsabilidade acompanhar as altera\u00e7\u00f5es no nosso site.<\/p>\n<p><strong>SE\u00c7\u00c3O 4 &#8211; ALTERA\u00c7\u00d5ES DO SERVI\u00c7O E DOS PRE\u00c7OS<\/strong><\/p>\n<p>Os pre\u00e7os de nossos produtos est\u00e3o sujeitos a altera\u00e7\u00f5es sem aviso pr\u00e9vio.<\/p>\n<p>Reservamo-nos o direito de, a qualquer momento, modificar ou descontinuar o Servi\u00e7o (ou qualquer parte ou conte\u00fado do mesmo) sem aviso pr\u00e9vio em qualquer momento.<\/p>\n<p>N\u00e3o nos responsabilizamos por voc\u00ea ou por qualquer terceiro por qualquer modifica\u00e7\u00e3o, altera\u00e7\u00e3o de pre\u00e7o, suspens\u00e3o ou descontinua\u00e7\u00e3o do Servi\u00e7o.<\/p>\n<p><strong>SE\u00c7\u00c3O 5 &#8211; PRODUTOS OU SERVI\u00c7OS (se aplic\u00e1vel)<\/strong><\/p>\n<p>Certos produtos ou servi\u00e7os podem estar dispon\u00edveis exclusivamente online atrav\u00e9s do site. Tais produtos ou servi\u00e7os podem ter quantidades limitadas e s\u00e3o sujeitos a apenas devolu\u00e7\u00e3o ou troca, de acordo com nossa Pol\u00edtica de devolu\u00e7\u00e3o.<\/p>\n<p>Fizemos todo o esfor\u00e7o poss\u00edvel para exibir da forma mais precisa as cores e imagens dos nossos produtos que aparecem na loja. N\u00e3o podemos garantir que a exibi\u00e7\u00e3o de qualquer cor no monitor do seu computador ser\u00e1 precisa.Reservamo-nos o direito de, mas n\u00e3o somos obrigados a, limitar as vendas de nossos produtos ou Servi\u00e7os para qualquer pessoa, regi\u00e3o geogr\u00e1fica ou jurisdi\u00e7\u00e3o. Podemos exercer esse direito conforme cada caso individual. Reservamo-nos o direito de limitar as quantidades de quaisquer produtos ou servi\u00e7os que oferecemos. Todas as descri\u00e7\u00f5es de produtos ou pre\u00e7os de produtos s\u00e3o sujeitos a altera\u00e7\u00e3o a qualquer momento sem aviso pr\u00e9vio, a nosso crit\u00e9rio exclusivo. Reservamo-nos o direito de descontinuar qualquer produto a qualquer momento. Qualquer oferta de produtos ou servi\u00e7os neste site \u00e9 nula onde for proibido por lei.<\/p>\n<p>N\u00e3o garantimos que a qualidade de quaisquer produtos, servi\u00e7os, informa\u00e7\u00f5es ou outros materiais comprados ou obtidos por voc\u00ea v\u00e3o atender \u00e0s suas expectativas, ou que quaisquer erros no Servi\u00e7o ser\u00e3o corrigidos.<\/p>\n<p><strong>SE\u00c7\u00c3O 6 &#8211; PRECIS\u00c3O DE COBRAN\u00c7A E INFORMA\u00c7\u00d5ES DA CONTA<\/strong><\/p>\n<p>N\u00f3s nos reservamos o direito de recusar qualquer pedido que voc\u00ea fizer conosco. Podemos, a nosso pr\u00f3prio crit\u00e9rio, limitar ou cancelar o n\u00famero de produtos comprados por pessoa, por domic\u00edlio ou por pedido. Tais restri\u00e7\u00f5es podem incluir pedidos feitos na mesma conta de cliente, no mesmo cart\u00e3o de cr\u00e9dito, e\/ou pedidos que usem a mesma fatura e\/ou endere\u00e7o de entrega. Caso fa\u00e7amos uma altera\u00e7\u00e3o ou cancelemos um pedido, podemos tentar notific\u00e1-lo entrando em contato com o endere\u00e7o de e-mail e\/ou o n\u00famero de telefone\/endere\u00e7o de faturamento fornecido no momento em que o pedido foi feito. Reservamo-nos o direito de limitar ou proibir pedidos que, a nosso crit\u00e9rio exclusivo, pare\u00e7am ter sido feitos por lojistas, revendedores ou distribuidores.Voc\u00ea concorda em fornecer suas informa\u00e7\u00f5es de conta e compra completas para todas as compras feitas em nossa loja. Voc\u00ea concorda em atualizar prontamente sua conta e outras informa\u00e7\u00f5es, incluindo seu e-mail, n\u00fameros de cart\u00e3o de cr\u00e9dito e datas de validade, para que possamos completar suas transa\u00e7\u00f5es e contatar voc\u00ea quando preciso.<\/p>\n<p>Para mais informa\u00e7\u00f5es, por favor, veja nossa Pol\u00edtica de devolu\u00e7\u00e3o.<\/p>\n<p><strong>SE\u00c7\u00c3O 7 &#8211; FERRAMENTAS OPCIONAIS<\/strong><\/p>\n<p>Podemos fornecer a voc\u00ea acesso a ferramentas de terceiros sobre as quais n\u00e3o monitoramos nem temos controle ou entrada.<\/p>\n<p>Voc\u00ea reconhece e concorda que n\u00f3s fornecemos acesso a tais ferramentas no estado em que se encontram e conforme a disponibilidade, sem quaisquer garantias, declara\u00e7\u00f5es ou condi\u00e7\u00f5es de qualquer tipo e sem qualquer endosso. N\u00e3o nos responsabilizamos de forma alguma pelo seu uso de ferramentas opcionais de terceiros.<\/p>\n<p>O uso de ferramentas opcionais oferecidas por meio do site \u00e9 inteiramente por sua conta e risco, e voc\u00ea deve se familiarizar e aprovar os termos das ferramentas que s\u00e3o fornecidas por fornecedor(es) terceiro(s).<\/p>\n<p>Tamb\u00e9m podemos, futuramente, oferecer novos servi\u00e7os e\/ou recursos por meio do site (incluindo o lan\u00e7amento de novas ferramentas e recursos). Tais recursos e\/ou servi\u00e7os novos tamb\u00e9m devem estar sujeitos a esses Termos de servi\u00e7o.<\/p>\n<p><strong>SE\u00c7\u00c3O 8 &#8211; LINKS DE TERCEIROS<\/strong><\/p>\n<p>Determinados conte\u00fados, produtos e servi\u00e7os dispon\u00edveis atrav\u00e9s do nosso Servi\u00e7o podem incluir materiais de terceiros.<\/p>\n<p>Os links de terceiros nesse site podem direcionar voc\u00ea a sites de terceiros que n\u00e3o s\u00e3o Afiliados a n\u00f3s. N\u00e3o nos responsabilizamos por examinar ou avaliar o conte\u00fado ou sua precis\u00e3o. N\u00e3o garantimos e nem temos obriga\u00e7\u00e3o ou responsabilidade por quaisquer materiais ou sites de terceiros, ou por quaisquer outros materiais, produtos ou servi\u00e7os de terceiros.<\/p>\n<p>N\u00e3o somos respons\u00e1veis por quaisquer danos ou preju\u00edzos relacionados com a compra ou uso de mercadorias, servi\u00e7os, recursos, conte\u00fado, ou quaisquer outras transa\u00e7\u00f5es feitas em conex\u00e3o com quaisquer sites de terceiros. Por favor, leia com cuidado as pol\u00edticas e pr\u00e1ticas de terceiros e certifique-se de que voc\u00ea as entende antes de efetuar qualquer transa\u00e7\u00e3o. As queixas, reclama\u00e7\u00f5es, preocupa\u00e7\u00f5es ou quest\u00f5es relativas a produtos de terceiros devem ser direcionadas \u00e0 respectiva empresa terceira.<\/p>\n<p><strong>SE\u00c7\u00c3O 9 &#8211; COMENT\u00c1RIOS, FEEDBACK E OUTRAS INTERA\u00c7\u00d5ES DO USU\u00c1RIO<\/strong><\/p>\n<p>Se, a nosso pedido, voc\u00ea executar determinadas a\u00e7\u00f5es espec\u00edficas (por exemplo, inscri\u00e7\u00f5es em concursos) ou, sem solicita\u00e7\u00e3o de nossa parte, enviar ideias criativas, sugest\u00f5es, propostas, planos ou outros materiais, seja online, por e-mail, correio ou de outra forma (em conjunto designados &#8220;coment\u00e1rios&#8221;), voc\u00ea concorda que podemos, a qualquer momento, sem restri\u00e7\u00f5es, editar, copiar, publicar, distribuir, traduzir e usar, em qualquer meio, quaisquer coment\u00e1rios que voc\u00ea encaminhar para n\u00f3s. N\u00e3o nos responsabilizamos por: (1) manter quaisquer coment\u00e1rios em sigilo; (2) indenizar por quaisquer coment\u00e1rios; ou (3) responder quaisquer coment\u00e1rios.Podemos, mas n\u00e3o temos a obriga\u00e7\u00e3o, de monitorar, editar ou remover conte\u00fado que n\u00f3s determinamos a nosso pr\u00f3prio crit\u00e9rio ser contra a lei, ofensivo, amea\u00e7ador, calunioso, difamat\u00f3rio, pornogr\u00e1fico, obsceno ou censur\u00e1vel, ou que viole a propriedade intelectual de terceiros ou estes Termos de servi\u00e7o.Voc\u00ea concorda que seus coment\u00e1rios n\u00e3o violar\u00e3o qualquer direito de terceiros, incluindo direitos autorais, marcas registradas, privacidade, personalidade ou outro direito pessoal ou de propriedade. Voc\u00ea concorda que os seus coment\u00e1rios n\u00e3o conter\u00e3o material difamat\u00f3rio, ilegal, abusivo ou obsceno. Eles tamb\u00e9m n\u00e3o conter\u00e3o nenhum v\u00edrus de computador ou outro malware que possa afetar a opera\u00e7\u00e3o do Servi\u00e7o ou qualquer site relacionado. Voc\u00ea n\u00e3o poder\u00e1 usar endere\u00e7o de e-mail falso, fingir ser algu\u00e9m diferente de si mesmo ou, de outra forma, enganar a n\u00f3s ou terceiros quanto \u00e0 origem de quaisquer coment\u00e1rios. Voc\u00ea \u00e9 o \u00fanico respons\u00e1vel por quaisquer coment\u00e1rios que faz e pela veracidade deles. N\u00f3s n\u00e3o assumimos qualquer responsabilidade ou obriga\u00e7\u00e3o por quaisquer coment\u00e1rios publicados por voc\u00ea ou por terceiros.<\/p>\n<p><strong>SE\u00c7\u00c3O 10 &#8211; INFORMA\u00c7\u00d5ES PESSOAIS<\/strong><\/p>\n<p>Sua apresenta\u00e7\u00e3o de informa\u00e7\u00f5es pessoais por meio da loja \u00e9 regida pela nossa Pol\u00edtica de privacidade. Consulte a nossa Pol\u00edtica de privacidade.<\/p>\n<p><strong>SE\u00c7\u00c3O 11 &#8211; ERROS, IMPRECIS\u00d5ES E OMISS\u00d5ES<\/strong><\/p>\n<p>Por vezes, pode haver informa\u00e7\u00f5es em nosso site ou no Servi\u00e7o que contenham erros tipogr\u00e1ficos, imprecis\u00f5es ou omiss\u00f5es que possam estar relacionadas a descri\u00e7\u00f5es de produtos, pre\u00e7os, promo\u00e7\u00f5es, ofertas, cobran\u00e7as de frete de produtos, tempos de tr\u00e2nsito e disponibilidade. Reservamo-nos o direito de corrigir quaisquer erros, imprecis\u00f5es ou omiss\u00f5es, e de alterar ou atualizar informa\u00e7\u00f5es ou cancelar pedidos caso qualquer informa\u00e7\u00e3o no Servi\u00e7o ou em qualquer site relacionado seja imprecisa, a qualquer momento e sem aviso pr\u00e9vio (at\u00e9 mesmo depois de voc\u00ea ter enviado o seu pedido).<\/p>\n<p>N\u00e3o assumimos nenhuma obriga\u00e7\u00e3o de atualizar, alterar ou explicar informa\u00e7\u00f5es no Servi\u00e7o ou em qualquer site relacionado, incluindo, entre outras, as informa\u00e7\u00f5es sobre pre\u00e7os, exceto conforme exigido por lei. Nenhuma atualiza\u00e7\u00e3o espec\u00edfica ou data de atualiza\u00e7\u00e3o no Servi\u00e7o ou em qualquer site relacionado deve ser utilizada para indicar que todas as informa\u00e7\u00f5es do Servi\u00e7o ou em qualquer site relacionado tenham sido modificadas ou atualizadas.<\/p>\n<p><strong>SE\u00c7\u00c3O 12 &#8211; USOS PROIBIDOS<\/strong><\/p>\n<p>Al\u00e9m de outras proibi\u00e7\u00f5es estabelecidas nos Termos de servi\u00e7o, voc\u00ea est\u00e1 proibido de usar o site ou seu conte\u00fado para: (a) qualquer finalidade il\u00edcita; (b) solicitar a outros que realizem ou participem de atos ilegais; (c) violar quaisquer regulamentos, regras, leis ou leis locais, internacionais, federais, municipais ou estaduais; (d) infringir ou violar nossos direitos de propriedade intelectual ou os direitos de propriedade intelectual de terceiros; (e) assediar, abusar, insultar, prejudicar, difamar, caluniar, desacreditar, intimidar ou discriminar com base no g\u00eanero, orienta\u00e7\u00e3o sexual, religi\u00e3o, etnia, ra\u00e7a, idade, nacionalidade ou defici\u00eancia; (f) apresentar informa\u00e7\u00f5es falsas ou enganosas;(g) enviar ou transmitir v\u00edrus ou qualquer outro tipo de c\u00f3digo malicioso, que ser\u00e1 ou poder\u00e1 ser usado de qualquer forma que afete a funcionalidade ou opera\u00e7\u00e3o do Servi\u00e7o ou de qualquer site relacionado, outros sites ou a internet; (h) coletar ou rastrear as informa\u00e7\u00f5es pessoais de terceiros; (i) pr\u00e1tica de spam, phishing, pharm, pretext, spider, crawl ou scrape; (j) qualquer prop\u00f3sito obsceno ou imoral; ou para (k) interferir ou contornar os recursos de seguran\u00e7a do Servi\u00e7o ou de qualquer site relacionado, outros sites ou a internet. Reservamo-nos o direito de rescindir o seu uso do Servi\u00e7o ou de qualquer site relacionado por violar qualquer um dos usos proibidos.<\/p>\n<p><strong>SE\u00c7\u00c3O 13 &#8211; ISEN\u00c7\u00c3O DE GARANTIAS; LIMITA\u00c7\u00c3O DE RESPONSABILIDADE<\/strong><\/p>\n<p>N\u00f3s n\u00e3o prometemos, representamos ou garantimos que seu uso de nosso servi\u00e7o ser\u00e1 ininterrupto, oportuno, seguro ou livre de erros.<br \/>\nN\u00e3o garantimos que os resultados que possam ser obtidos pelo uso do servi\u00e7o ser\u00e3o precisos ou confi\u00e1veis.<\/p>\n<p>Voc\u00ea concorda que, de tempos em tempos, podemos remover o servi\u00e7o por per\u00edodos indefinidos de tempo ou cancel\u00e1-lo a qualquer momento, sem enviar aviso pr\u00e9vio para voc\u00ea.Voc\u00ea concorda que o seu uso ou incapacidade de usar o servi\u00e7o \u00e9 por sua conta e risco. O servi\u00e7o e todos os produtos e servi\u00e7os entregues atrav\u00e9s do servi\u00e7o s\u00e3o (exceto conforme declarado por n\u00f3s) fornecidos sem garantia e conforme a disponibilidade para seu uso, sem qualquer declara\u00e7\u00e3o, garantias ou condi\u00e7\u00f5es de qualquer tipo, expressas ou impl\u00edcitas, incluindo todas as garantias impl\u00edcitas ou condi\u00e7\u00f5es de comercializa\u00e7\u00e3o, quantidade, adequa\u00e7\u00e3o a uma finalidade espec\u00edfica, durabilidade, t\u00edtulo e n\u00e3o viola\u00e7\u00e3o.Em nenhum caso, a , nossos diretores, executivos, funcion\u00e1rios, Afiliados, agentes, contratados, estagi\u00e1rios, fornecedores, provedores de servi\u00e7os ou licenciantes ser\u00e3o respons\u00e1veis por qualquer dano, perda, reivindica\u00e7\u00e3o ou qualquer dano direto, indireto, incidental, punitivo, especial ou consequencial de qualquer tipo, incluindo, entre outros, lucros perdidos, perda de receita, perda de economias, perda de dados, custos de substitui\u00e7\u00e3o ou quaisquer danos semelhantes, seja com base em contrato, ato il\u00edcito (incluindo neglig\u00eancia), responsabilidade estrita ou n\u00e3o, decorrentes do uso de qualquer um dos servi\u00e7os ou quaisquer produtos adquiridos usando o servi\u00e7o, ou para qualquer outra reivindica\u00e7\u00e3o relacionada de qualquer forma ao seu uso do servi\u00e7o ou qualquer produto, incluindo, entre outros, quaisquer erros ou omiss\u00f5es em qualquer conte\u00fado, ou qualquer perda ou dano de qualquer tipo incorrido como resultado do uso do servi\u00e7o ou de qualquer conte\u00fado (ou produto) publicado, transmitido ou de outra forma disponibilizado atrav\u00e9s do servi\u00e7o, mesmo se avisado de sua possibilidade.Como alguns estados ou jurisdi\u00e7\u00f5es n\u00e3o permitem a exclus\u00e3o ou a limita\u00e7\u00e3o de responsabilidade por danos indiretos ou incidentais, em tais estados ou jurisdi\u00e7\u00f5es, a nossa responsabilidade ser\u00e1 limitada \u00e0 extens\u00e3o m\u00e1xima permitida por lei.<\/p>\n<p><strong>SE\u00c7\u00c3O 14 &#8211; INDENIZA\u00c7\u00c3O<\/strong><\/p>\n<p>Voc\u00ea concorda em indenizar, defender e isentar  e nossa matriz, subsidi\u00e1rias, afiliadas, parceiros, executivos, diretores, agentes, contratados, licenciantes, prestadores de servi\u00e7os, subcontratados, fornecedores, estagi\u00e1rios e funcion\u00e1rios, de qualquer reivindica\u00e7\u00e3o ou demanda, incluindo honor\u00e1rios advocat\u00edcios razo\u00e1veis, feitos por terceiros, devido a ou decorrente de sua viola\u00e7\u00e3o destes Termos de servi\u00e7o ou dos documentos que incorporam por refer\u00eancia, ou sua viola\u00e7\u00e3o de qualquer lei ou dos direitos de terceiros.<\/p>\n<p><strong>SE\u00c7\u00c3O 15 &#8211; INDEPEND\u00caNCIA<\/strong><\/p>\n<p>No caso de qualquer disposi\u00e7\u00e3o destes Termos de servi\u00e7o ser considerada ilegal, nula ou inexequ\u00edvel, tal disposi\u00e7\u00e3o ser\u00e1, no entanto, execut\u00e1vel na extens\u00e3o m\u00e1xima permitida pela lei aplic\u00e1vel, e a parte inexequ\u00edvel ser\u00e1 considerada como cortada destes Termos de servi\u00e7o, e tal determina\u00e7\u00e3o n\u00e3o afetar\u00e1 a validade e aplicabilidade de quaisquer outras disposi\u00e7\u00f5es remanescentes.<\/p>\n<p><strong>SE\u00c7\u00c3O 16 &#8211; RESCIS\u00c3O<\/strong><\/p>\n<p>As obriga\u00e7\u00f5es e as responsabilidades das partes incorridas antes da data de rescis\u00e3o sobreviver\u00e3o \u00e0 rescis\u00e3o deste contrato para todos os fins.<\/p>\n<p>Estes Termos de servi\u00e7o permanecem em vigor, a menos que sejam rescindidos por voc\u00ea ou por n\u00f3s. Voc\u00ea pode rescindir estes Termos de servi\u00e7o a qualquer momento, notificando-nos que j\u00e1 n\u00e3o deseja utilizar os nossos servi\u00e7os, ou quando voc\u00ea deixar de usar o nosso site.Se em nosso crit\u00e9rio exclusivo voc\u00ea n\u00e3o cumprir com qualquer termo ou disposi\u00e7\u00e3o destes Termos de servi\u00e7o, n\u00f3s tamb\u00e9m podemos rescindir este contrato a qualquer momento sem aviso pr\u00e9vio e voc\u00ea ficar\u00e1 respons\u00e1vel por todas as quantias devidas at\u00e9 a data da rescis\u00e3o; tamb\u00e9m podemos lhe negar acesso a nossos Servi\u00e7os (ou qualquer parte deles).<\/p>\n<p><strong>SE\u00c7\u00c3O 17 &#8211; ACORDO INTEGRAL<\/strong><\/p>\n<p>A falha de nossa parte em exercer ou executar qualquer direito ou disposi\u00e7\u00e3o destes Termos de Servi\u00e7o n\u00e3o constituir\u00e1 uma ren\u00fancia de tal direito ou disposi\u00e7\u00e3o.<\/p>\n<p>Estes Termos de servi\u00e7o e quaisquer pol\u00edticas ou normas operacionais publicadas por n\u00f3s neste site ou no que diz respeito ao servi\u00e7o constituem a totalidade do acordo entre n\u00f3s. Estes termos regem o seu uso do Servi\u00e7o, substituindo quaisquer acordos anteriores ou contempor\u00e2neos, comunica\u00e7\u00f5es e propostas, sejam verbais ou escritos, entre voc\u00ea e n\u00f3s (incluindo, entre outros, quaisquer vers\u00f5es anteriores dos Termos de servi\u00e7o).Quaisquer ambiguidades na interpreta\u00e7\u00e3o destes Termos de servi\u00e7o n\u00e3o devem ser interpretadas contra a parte que os redigiu.<\/p>\n<p><strong>SE\u00c7\u00c3O 18 &#8211; LEGISLA\u00c7\u00c3O APLIC\u00c1VEL<\/strong><\/p>\n<p>Estes Termos de servi\u00e7o e quaisquer contratos separados nos quais fornecemos a voc\u00ea os Servi\u00e7os ser\u00e3o regidos e interpretados de acordo com as leis brasileiras.<\/p>\n<p><strong>SE\u00c7\u00c3O 19 &#8211; MUDAN\u00c7AS NOS TERMOS DE SERVI\u00c7O<\/strong><\/p>\n<p>Voc\u00ea pode revisar a vers\u00e3o mais atual dos Termos de servi\u00e7o a qualquer momento nesta p\u00e1gina.<\/p>\n<p>Reservamo-nos o direito, a nosso crit\u00e9rio, de atualizar, modificar ou substituir qualquer parte destes Termos de servi\u00e7o ao publicar atualiza\u00e7\u00f5es e altera\u00e7\u00f5es no nosso site. \u00c9 sua responsabilidade verificar periodicamente se h\u00e1 altera\u00e7\u00f5es em nosso site. Seu uso cont\u00ednuo ou acesso ao nosso site ou ao Servi\u00e7o ap\u00f3s a publica\u00e7\u00e3o de quaisquer altera\u00e7\u00f5es a estes Termos de servi\u00e7o constitui aceita\u00e7\u00e3o dessas altera\u00e7\u00f5es.<\/p>\n<p><strong>SE\u00c7\u00c3O 20 &#8211; INFORMA\u00c7\u00d5ES DE CONTATO<\/strong><\/p>\n<p>Perguntas sobre os Termos de servi\u00e7o devem ser enviadas para n\u00f3s em <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Termos de Uso<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-331","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Termos de Uso - Root<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termos de Uso - Root\" \/>\n<meta property=\"og:description\" content=\"Termos de Uso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/\" \/>\n<meta property=\"og:site_name\" content=\"Root\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T20:26:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/termos-de-uso\\\/\",\"url\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/termos-de-uso\\\/\",\"name\":\"Termos de Uso - Root\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/#website\"},\"datePublished\":\"2021-03-05T12:53:38+00:00\",\"dateModified\":\"2021-09-30T20:26:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/termos-de-uso\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/termos-de-uso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/termos-de-uso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termos de Uso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/#website\",\"url\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/\",\"name\":\"Root\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojashopbase.com.br\\\/spark\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termos de Uso - Root","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/","og_locale":"pt_BR","og_type":"article","og_title":"Termos de Uso - Root","og_description":"Termos de Uso","og_url":"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/","og_site_name":"Root","article_modified_time":"2021-09-30T20:26:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/","url":"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/","name":"Termos de Uso - Root","isPartOf":{"@id":"https:\/\/lojashopbase.com.br\/spark\/#website"},"datePublished":"2021-03-05T12:53:38+00:00","dateModified":"2021-09-30T20:26:08+00:00","breadcrumb":{"@id":"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lojashopbase.com.br\/spark\/termos-de-uso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojashopbase.com.br\/spark\/"},{"@type":"ListItem","position":2,"name":"Termos de Uso"}]},{"@type":"WebSite","@id":"https:\/\/lojashopbase.com.br\/spark\/#website","url":"https:\/\/lojashopbase.com.br\/spark\/","name":"Root","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojashopbase.com.br\/spark\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/pages\/331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/comments?post=331"}],"version-history":[{"count":0,"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/pages\/331\/revisions"}],"wp:attachment":[{"href":"https:\/\/lojashopbase.com.br\/spark\/wp-json\/wp\/v2\/media?parent=331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}